{"id":10954,"date":"2020-12-22T18:41:27","date_gmt":"2020-12-22T17:41:27","guid":{"rendered":"http:\/\/lesnik-lenart.si\/traktor\/deutz-agrolux-310-320-410\/"},"modified":"2020-12-22T18:41:27","modified_gmt":"2020-12-22T17:41:27","slug":"deutz-agrolux-310-320-410","status":"publish","type":"traktor","link":"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/","title":{"rendered":"DEUTZ AGROLUX 310-320-410"},"content":{"rendered":"<p>\u2022\u00a0Puissance de levage 1700-2500kg,\u00a0mesur\u00e9 en crochets<br \/>\n\u2022\u00a0Cat\u00e9gorie \u2013 largeur de Cat.2<br \/>\n\u2022 Bras de levage repliables (position de transport) et amovibles<br \/>\n\u2022 Bras de levage bilat\u00e9raux attel\u00e9s de mani\u00e8re pivotante pouvant \u00eatre fix\u00e9s \u2013 position flottante et position fixe<br \/>\n\u2022 Syst\u00e8me hydraulique fonctionnant dans les deux sens<br \/>\n\u2022 Crochets Walterscheid pour une connexion rapide de Cat.2<br \/>\n\u2022 Anneau de traction<br \/>\n\u2022 Support de barre d\u2019attelage (du levier central)<br \/>\n\u2022 Tuyaux hydrauliques avec coupleurs rapides et valve de fermeture dans le tuyau de levage<\/p>\n","protected":false},"featured_media":0,"template":"","serija":[301],"znamka":[166],"class_list":["post-10954","traktor","type-traktor","status-publish","hentry","serija-deutz-fahr-agrolux","znamka-deutz-fahr-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DEUTZ AGROLUX 310-320-410 - Le\u0161nik Lenart<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DEUTZ AGROLUX 310-320-410 - Le\u0161nik Lenart\" \/>\n<meta property=\"og:description\" content=\"\u2022\u00a0Puissance de levage 1700-2500kg,\u00a0mesur\u00e9 en crochets \u2022\u00a0Cat\u00e9gorie \u2013 largeur de Cat.2 \u2022 Bras de levage repliables (position de transport) et amovibles \u2022 Bras de levage bilat\u00e9raux attel\u00e9s de mani\u00e8re pivotante pouvant \u00eatre fix\u00e9s \u2013 position flottante et position fixe \u2022 Syst\u00e8me hydraulique fonctionnant dans les deux sens \u2022 Crochets Walterscheid pour une connexion rapide de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/\" \/>\n<meta property=\"og:site_name\" content=\"Le\u0161nik Lenart\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/tracteur\\\/deutz-agrolux-310-320-410\\\/\",\"url\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/tracteur\\\/deutz-agrolux-310-320-410\\\/\",\"name\":\"DEUTZ AGROLUX 310-320-410 - Le\u0161nik Lenart\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/#website\"},\"datePublished\":\"2020-12-22T17:41:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/tracteur\\\/deutz-agrolux-310-320-410\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/tracteur\\\/deutz-agrolux-310-320-410\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/tracteur\\\/deutz-agrolux-310-320-410\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tracteur\",\"item\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/tracteur\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DEUTZ AGROLUX 310-320-410\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/\",\"name\":\"Le\u0161nik Lenart\",\"description\":\"Le\u0161nik Lenart\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/#organization\",\"name\":\"Le\u0161nik Lenart\",\"url\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lesnik-lenart.si\\\/wp-content\\\/uploads\\\/elementi\\\/lesnik-lenart-logo-rdeca.svg\",\"contentUrl\":\"http:\\\/\\\/lesnik-lenart.si\\\/wp-content\\\/uploads\\\/elementi\\\/lesnik-lenart-logo-rdeca.svg\",\"width\":914,\"height\":139,\"caption\":\"Le\u0161nik Lenart\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DEUTZ AGROLUX 310-320-410 - Le\u0161nik Lenart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/","og_locale":"fr_FR","og_type":"article","og_title":"DEUTZ AGROLUX 310-320-410 - Le\u0161nik Lenart","og_description":"\u2022\u00a0Puissance de levage 1700-2500kg,\u00a0mesur\u00e9 en crochets \u2022\u00a0Cat\u00e9gorie \u2013 largeur de Cat.2 \u2022 Bras de levage repliables (position de transport) et amovibles \u2022 Bras de levage bilat\u00e9raux attel\u00e9s de mani\u00e8re pivotante pouvant \u00eatre fix\u00e9s \u2013 position flottante et position fixe \u2022 Syst\u00e8me hydraulique fonctionnant dans les deux sens \u2022 Crochets Walterscheid pour une connexion rapide de [&hellip;]","og_url":"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/","og_site_name":"Le\u0161nik Lenart","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/","url":"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/","name":"DEUTZ AGROLUX 310-320-410 - Le\u0161nik Lenart","isPartOf":{"@id":"https:\/\/www.lesnik-lenart.si\/fr\/#website"},"datePublished":"2020-12-22T17:41:27+00:00","breadcrumb":{"@id":"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/deutz-agrolux-310-320-410\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lesnik-lenart.si\/fr\/"},{"@type":"ListItem","position":2,"name":"Tracteur","item":"https:\/\/www.lesnik-lenart.si\/fr\/tracteur\/"},{"@type":"ListItem","position":3,"name":"DEUTZ AGROLUX 310-320-410"}]},{"@type":"WebSite","@id":"https:\/\/www.lesnik-lenart.si\/fr\/#website","url":"https:\/\/www.lesnik-lenart.si\/fr\/","name":"Le\u0161nik Lenart","description":"Le\u0161nik Lenart","publisher":{"@id":"https:\/\/www.lesnik-lenart.si\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesnik-lenart.si\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesnik-lenart.si\/fr\/#organization","name":"Le\u0161nik Lenart","url":"https:\/\/www.lesnik-lenart.si\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesnik-lenart.si\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/lesnik-lenart.si\/wp-content\/uploads\/elementi\/lesnik-lenart-logo-rdeca.svg","contentUrl":"http:\/\/lesnik-lenart.si\/wp-content\/uploads\/elementi\/lesnik-lenart-logo-rdeca.svg","width":914,"height":139,"caption":"Le\u0161nik Lenart"},"image":{"@id":"https:\/\/www.lesnik-lenart.si\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesnik-lenart.si\/fr\/wp-json\/wp\/v2\/traktor\/10954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesnik-lenart.si\/fr\/wp-json\/wp\/v2\/traktor"}],"about":[{"href":"https:\/\/www.lesnik-lenart.si\/fr\/wp-json\/wp\/v2\/types\/traktor"}],"version-history":[{"count":0,"href":"https:\/\/www.lesnik-lenart.si\/fr\/wp-json\/wp\/v2\/traktor\/10954\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesnik-lenart.si\/fr\/wp-json\/wp\/v2\/media?parent=10954"}],"wp:term":[{"taxonomy":"serija","embeddable":true,"href":"https:\/\/www.lesnik-lenart.si\/fr\/wp-json\/wp\/v2\/serija?post=10954"},{"taxonomy":"znamka","embeddable":true,"href":"https:\/\/www.lesnik-lenart.si\/fr\/wp-json\/wp\/v2\/znamka?post=10954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}