{"id":4791,"date":"2020-12-20T19:32:01","date_gmt":"2020-12-20T18:32:01","guid":{"rendered":"http:\/\/lesnik-lenart.si\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/"},"modified":"2026-05-06T14:34:30","modified_gmt":"2026-05-06T12:34:30","slug":"leichte-schneepfluge","status":"publish","type":"page","link":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/","title":{"rendered":"Leichte Schneepfluge"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4791\" class=\"elementor elementor-4791 elementor-528\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-150f9a7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"150f9a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56ff496\" data-id=\"56ff496\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5401b02 elementor-widget elementor-widget-template\" data-id=\"5401b02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"1561\" class=\"elementor elementor-1561\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-dce-background-image-url=\"http:\/\/lesnik-lenart.si\/wp-content\/uploads\/elementi\/ozadje-trikotniki-temno-1600px.jpg\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2b15989 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b15989\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9b492f\" data-id=\"f9b492f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-color=\"#FFFFFF\" class=\"elementor-section elementor-top-section elementor-element elementor-element-487ab9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"487ab9f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1eb9302\" data-id=\"1eb9302\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d519d78 elementor-widget elementor-widget-breadcrumbs\" data-id=\"d519d78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.lesnik-lenart.si\/de\/\">Zuhause<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-overlay-image-url=\"http:\/\/lesnik-lenart.si\/wp-content\/uploads\/elementi\/sive-crte.svg\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0bfefde elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bfefde\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31bd992\" data-id=\"31bd992\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e30735b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e30735b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e7bb19\" data-id=\"1e7bb19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec93502 elementor-widget elementor-widget-heading\" data-id=\"ec93502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SPA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-425e916 elementor-widget elementor-widget-text-editor\" data-id=\"425e916\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SPA &#8211; Leichte Ausf\u00fchrung. F\u00fcr Traktoren bis ca. 90 PS<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ade46a0\" data-id=\"ade46a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db0068c elementor-widget elementor-widget-image\" data-id=\"db0068c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"508\" src=\"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png\" class=\"attachment-large size-large wp-image-4015\" alt=\"Leichtes Schneepflug\" srcset=\"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png 1024w, https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2-300x190.png 300w, https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2-768x488.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bafc4a elementor-widget elementor-widget-heading\" data-id=\"0bafc4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SPA Modelle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17774bd elementor-widget elementor-widget-jet-table\" data-id=\"17774bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-table jet-elements\">\n\t\t<div class=\"jet-table-wrapper jet-table-responsive-mobile\">\n\t\t\t<table class=\"jet-table jet-table--fa5-compat\">\n\t\t\t\t<thead class=\"jet-table__head\"><tr class=\"jet-table__head-row\"><th class=\"jet-table__cell elementor-repeater-item-4c17825 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Typ<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-4222cd5 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Pflugbreite<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-c249e39 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Pflugscharh\u00f6he<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-71d3395 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Anzahl Pflugscharen<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-cfc4390 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">R\u00e4umbreite bei 30\u00b0<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-145a295 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Eigengewicht<\/div><\/div><\/div><\/th><\/tr><\/thead>\n\t\t\t\t\t\t\t\t<tbody class=\"jet-table__body\"><tr class=\"jet-table__body-row elementor-repeater-item-b252066\"><td class=\"jet-table__cell elementor-repeater-item-dbc3e95 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">SPA 25-2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-b00d09b jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2500 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-e15d991 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">850 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-f1ca965 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-0654bfc jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2165 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-6fd3cb3 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">560 kg<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-8a9fd9c\"><td class=\"jet-table__cell elementor-repeater-item-45b0474 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">SPA 28-2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-7df8cf6 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2800 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-86799b7 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">850 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-2b029da jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-9eb1a26 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2425 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-342fd90 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">580 kg<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-f920790\"><td class=\"jet-table__cell elementor-repeater-item-810a1c9 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">SPA 30-2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-8afacf3 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">3000 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-767c12e jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">850 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-6260550 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-614bc23 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2600 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-4d42116 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">610 kg<\/div><\/div><\/div><\/td><\/tr><\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-103c673 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"103c673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.lesnik-lenart.si\/de\/anfrage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Brauchen Sie Hilfe?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de289d8 elementor-widget elementor-widget-heading\" data-id=\"de289d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SPA Ausstattung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f04cee7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f04cee7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9ac8876\" data-id=\"9ac8876\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48fb2c4 elementor-widget elementor-widget-heading\" data-id=\"48fb2c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Serienausstattung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f8e7d9 elementor-widget elementor-widget-text-editor\" data-id=\"1f8e7d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Schnellwechselplatte-pflugseitige Kuppelplatte<\/li>\n<li>hydraulische Seitenverstellung mit 2 Zylindern<\/li>\n<li>hydraulisches Heben<\/li>\n<li>1 oder 2 Pflugscharen (einteilig oder zweiteilig)<\/li>\n<li>\u00dcberfahrsicherung<\/li>\n<li>hydraulisches Sicherheitssystem-Schwenkd\u00e4mpfungsventil (Doppelschockventil)<\/li>\n<li>querpendlende Aufh\u00e4ngung-Pendelausgleich<\/li>\n<li>h\u00f6henverstellbare Gleitteller<\/li>\n<li>geschraubte Sch\u00fcrfleiste aus Stahl<\/li>\n<li>Randsteinabweiser<\/li>\n<li>Anschlu\u00dfleitungen und Kupplungen<\/li>\n<li>Abstellst\u00fctze<\/li>\n<li>Warnflaggen<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27c662e\" data-id=\"27c662e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df583dc elementor-widget elementor-widget-heading\" data-id=\"df583dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zusatzausr\u00fcstung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72b9d71 elementor-widget elementor-widget-text-editor\" data-id=\"72b9d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>stufenlos h\u00f6henverstellbare Laufr\u00e4der mit Vollgummireifen\u00a0statt Schleiftellern<\/li>\n<li>Schneeblende aus armierten Gummiband<\/li>\n<li>Sch\u00fcrfleiste aus geh\u00e4rtetem Stahl (HARDOX)<\/li>\n<li>Sch\u00fcrfleiste aus Kunststoff (Polyurethan)<\/li>\n<li>Pflugbeleuchtung<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-726f06d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"726f06d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f487cc\" data-id=\"7f487cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a3093d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3093d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b62c58d\" data-id=\"b62c58d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a0841f elementor-widget elementor-widget-heading\" data-id=\"7a0841f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SPA T<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-417cf47 elementor-widget elementor-widget-text-editor\" data-id=\"417cf47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SPA T Leichte Ausf\u00fchrung. F\u00fcr Traktoren bis ca. 90 PS.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e321c4\" data-id=\"1e321c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecd63ce elementor-widget elementor-widget-image\" data-id=\"ecd63ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"508\" src=\"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-3.png\" class=\"attachment-large size-large wp-image-4010\" alt=\"Leichtes Schneepflug\" srcset=\"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-3.png 1024w, https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-3-300x190.png 300w, https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-3-768x488.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7634c2e elementor-widget elementor-widget-heading\" data-id=\"7634c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SPA T Modelle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2a596b elementor-widget elementor-widget-jet-table\" data-id=\"a2a596b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-table jet-elements\">\n\t\t<div class=\"jet-table-wrapper jet-table-responsive-mobile\">\n\t\t\t<table class=\"jet-table jet-table--fa5-compat\">\n\t\t\t\t<thead class=\"jet-table__head\"><tr class=\"jet-table__head-row\"><th class=\"jet-table__cell elementor-repeater-item-4c17825 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Typ<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-4222cd5 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Pflugbreite<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-c249e39 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Pflugscharh\u00f6he<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-71d3395 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Anzahl Pflugscharen<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-cfc4390 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">R\u00e4umbreite bei 30\u00b0<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-145a295 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Eigengewicht<\/div><\/div><\/div><\/th><\/tr><\/thead>\n\t\t\t\t\t\t\t\t<tbody class=\"jet-table__body\"><tr class=\"jet-table__body-row elementor-repeater-item-b252066\"><td class=\"jet-table__cell elementor-repeater-item-dbc3e95 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">SPA T25-2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-b00d09b jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2500 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-e15d991 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">850 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-f1ca965 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-0654bfc jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2165 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-6fd3cb3 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">490 kg<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-8a9fd9c\"><td class=\"jet-table__cell elementor-repeater-item-45b0474 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">SPA T28-2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-7df8cf6 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2800 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-86799b7 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">850 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-2b029da jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-9eb1a26 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2425 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-342fd90 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">510 kg<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-f920790\"><td class=\"jet-table__cell elementor-repeater-item-810a1c9 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">SPA T30-2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-8afacf3 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">3000 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-767c12e jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">850 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-6260550 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-614bc23 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">2600 mm<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-4d42116 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">540 kg<\/div><\/div><\/div><\/td><\/tr><\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4f4d2d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c4f4d2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.lesnik-lenart.si\/de\/anfrage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Brauchen Sie Hilfe?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84be215 elementor-widget elementor-widget-heading\" data-id=\"84be215\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SPA T Ausstattung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7fbcd94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fbcd94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-73579f1\" data-id=\"73579f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50cac6b elementor-widget elementor-widget-heading\" data-id=\"50cac6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Serienausstattung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3346d02 elementor-widget elementor-widget-text-editor\" data-id=\"3346d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>f\u00fcr Fronthydraulik oder Heckhydraulik<\/li>\n<li>3-Punkt Aufh\u00e4ngung Kat.1 oder Kat.2<\/li>\n<li>hydraulische Seitenverstellung mit 2 Zylindern<\/li>\n<li>1 oder 2 Pflugscharen (einteilig oder zweiteilig)<\/li>\n<li>\u00dcberfahrsicherung<\/li>\n<li>hydraulisches Sicherheitssystem-Schwenkd\u00e4mpfungsventil (Doppelschockventil)<\/li>\n<li>querpendlende Aufh\u00e4ngung-Pendelausgleich<\/li>\n<li>h\u00f6henverstellbare Gleitteller<\/li>\n<li>geschraubte Sch\u00fcrfleiste aus Stahl<\/li>\n<li>Randsteinabweiser<\/li>\n<li>Anschlu\u00dfleitungen und Kupplungen<\/li>\n<li>Abstellst\u00fctze<\/li>\n<li>Warnflaggen<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c431f74\" data-id=\"c431f74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ba6d35 elementor-widget elementor-widget-heading\" data-id=\"5ba6d35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zusatzausr\u00fcstung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef92dce elementor-widget elementor-widget-text-editor\" data-id=\"ef92dce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>stufenlos h\u00f6henverstellbare Laufr\u00e4der mit Vollgummireifen\u00a0statt Schleiftellern<\/li>\n<li>Schneeblende aus armierten Gummiband<\/li>\n<li>Sch\u00fcrfleiste aus geh\u00e4rtetem Stahl (HARDOX)<\/li>\n<li>Sch\u00fcrfleiste aus Kunststoff (Polyurethan)<\/li>\n<li>Pflugbeleuchtung<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SPA SPA &#8211; Leichte Ausf\u00fchrung. F\u00fcr Traktoren bis ca. 90 PS SPA Modelle Typ Pflugbreite Pflugscharh\u00f6he Anzahl Pflugscharen R\u00e4umbreite bei 30\u00b0 Eigengewicht SPA 25-2 2500 mm 850 mm 2 2165 mm 560 kg SPA 28-2 2800 mm 850 mm 2 2425 mm 580 kg SPA 30-2 3000 mm 850 mm 2 2600 mm 610 kg [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":4787,"menu_order":212,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4791","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leichte Schneepfluge - Le\u0161nik Lenart<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leichte Schneepfluge - Le\u0161nik Lenart\" \/>\n<meta property=\"og:description\" content=\"SPA SPA &#8211; Leichte Ausf\u00fchrung. F\u00fcr Traktoren bis ca. 90 PS SPA Modelle Typ Pflugbreite Pflugscharh\u00f6he Anzahl Pflugscharen R\u00e4umbreite bei 30\u00b0 Eigengewicht SPA 25-2 2500 mm 850 mm 2 2165 mm 560 kg SPA 28-2 2800 mm 850 mm 2 2425 mm 580 kg SPA 30-2 3000 mm 850 mm 2 2600 mm 610 kg [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/\" \/>\n<meta property=\"og:site_name\" content=\"Le\u0161nik Lenart\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T12:34:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/leichte-schneepfluge\\\/\",\"url\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/leichte-schneepfluge\\\/\",\"name\":\"Leichte Schneepfluge - Le\u0161nik Lenart\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/leichte-schneepfluge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/leichte-schneepfluge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/wp-content\\\/uploads\\\/komunalna-oprema\\\/snezni-plugi\\\/lazji\\\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png\",\"datePublished\":\"2020-12-20T18:32:01+00:00\",\"dateModified\":\"2026-05-06T12:34:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/leichte-schneepfluge\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/leichte-schneepfluge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/leichte-schneepfluge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/wp-content\\\/uploads\\\/komunalna-oprema\\\/snezni-plugi\\\/lazji\\\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png\",\"contentUrl\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/wp-content\\\/uploads\\\/komunalna-oprema\\\/snezni-plugi\\\/lazji\\\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/leichte-schneepfluge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Zuhause\",\"item\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kommunalger\u00e4te\",\"item\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schneepfl\u00fcge\",\"item\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/kommunalgeraete\\\/schneepfluege\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Leichte Schneepfluge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/\",\"name\":\"Le\u0161nik Lenart\",\"description\":\"Le\u0161nik Lenart\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/#organization\",\"name\":\"Le\u0161nik Lenart\",\"url\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lesnik-lenart.si\\\/wp-content\\\/uploads\\\/elementi\\\/lesnik-lenart-logo-rdeca.svg\",\"contentUrl\":\"http:\\\/\\\/lesnik-lenart.si\\\/wp-content\\\/uploads\\\/elementi\\\/lesnik-lenart-logo-rdeca.svg\",\"width\":914,\"height\":139,\"caption\":\"Le\u0161nik Lenart\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesnik-lenart.si\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leichte Schneepfluge - Le\u0161nik Lenart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/","og_locale":"de_DE","og_type":"article","og_title":"Leichte Schneepfluge - Le\u0161nik Lenart","og_description":"SPA SPA &#8211; Leichte Ausf\u00fchrung. F\u00fcr Traktoren bis ca. 90 PS SPA Modelle Typ Pflugbreite Pflugscharh\u00f6he Anzahl Pflugscharen R\u00e4umbreite bei 30\u00b0 Eigengewicht SPA 25-2 2500 mm 850 mm 2 2165 mm 560 kg SPA 28-2 2800 mm 850 mm 2 2425 mm 580 kg SPA 30-2 3000 mm 850 mm 2 2600 mm 610 kg [&hellip;]","og_url":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/","og_site_name":"Le\u0161nik Lenart","article_modified_time":"2026-05-06T12:34:30+00:00","og_image":[{"width":1024,"height":650,"url":"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/","url":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/","name":"Leichte Schneepfluge - Le\u0161nik Lenart","isPartOf":{"@id":"https:\/\/www.lesnik-lenart.si\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/#primaryimage"},"image":{"@id":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png","datePublished":"2020-12-20T18:32:01+00:00","dateModified":"2026-05-06T12:34:30+00:00","breadcrumb":{"@id":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/#primaryimage","url":"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png","contentUrl":"https:\/\/www.lesnik-lenart.si\/wp-content\/uploads\/komunalna-oprema\/snezni-plugi\/lazji\/lazja-snezna-deska-snezni-plug-snezna-rampirka-lesnik-lenart-2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/leichte-schneepfluge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Zuhause","item":"https:\/\/www.lesnik-lenart.si\/de\/"},{"@type":"ListItem","position":2,"name":"Kommunalger\u00e4te","item":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/"},{"@type":"ListItem","position":3,"name":"Schneepfl\u00fcge","item":"https:\/\/www.lesnik-lenart.si\/de\/kommunalgeraete\/schneepfluege\/"},{"@type":"ListItem","position":4,"name":"Leichte Schneepfluge"}]},{"@type":"WebSite","@id":"https:\/\/www.lesnik-lenart.si\/de\/#website","url":"https:\/\/www.lesnik-lenart.si\/de\/","name":"Le\u0161nik Lenart","description":"Le\u0161nik Lenart","publisher":{"@id":"https:\/\/www.lesnik-lenart.si\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesnik-lenart.si\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lesnik-lenart.si\/de\/#organization","name":"Le\u0161nik Lenart","url":"https:\/\/www.lesnik-lenart.si\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lesnik-lenart.si\/de\/#\/schema\/logo\/image\/","url":"http:\/\/lesnik-lenart.si\/wp-content\/uploads\/elementi\/lesnik-lenart-logo-rdeca.svg","contentUrl":"http:\/\/lesnik-lenart.si\/wp-content\/uploads\/elementi\/lesnik-lenart-logo-rdeca.svg","width":914,"height":139,"caption":"Le\u0161nik Lenart"},"image":{"@id":"https:\/\/www.lesnik-lenart.si\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/pages\/4791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/comments?post=4791"}],"version-history":[{"count":3,"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/pages\/4791\/revisions"}],"predecessor-version":[{"id":25824,"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/pages\/4791\/revisions\/25824"}],"up":[{"embeddable":true,"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/pages\/4787"}],"wp:attachment":[{"href":"https:\/\/www.lesnik-lenart.si\/de\/wp-json\/wp\/v2\/media?parent=4791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}